{"id":13305,"date":"2019-09-02T17:38:52","date_gmt":"2019-09-02T22:38:52","guid":{"rendered":"https:\/\/www.openintl.com\/ambienteWordpress\/?page_id=13305"},"modified":"2023-06-09T10:19:15","modified_gmt":"2023-06-09T15:19:15","slug":"sistema-de-soporte-a-la-operacion","status":"publish","type":"page","link":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/","title":{"rendered":"OSS | Sistema de Soporte a la Operaci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13305\" class=\"elementor elementor-13305\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-44d280fb elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-eae-slider=\"56895\" data-id=\"44d280fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;curve-asymmetrical&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4044a915\" data-eae-slider=\"69051\" data-id=\"4044a915\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-458e0d5a elementor-widget elementor-widget-heading\" data-id=\"458e0d5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OSS | SISTEMA DE SOPORTE A LA OPERACI\u00d3N<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-65b11f33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"22666\" data-id=\"65b11f33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35fe4e34\" data-eae-slider=\"21393\" data-id=\"35fe4e34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291a3988 elementor-widget elementor-widget-text-editor\" data-id=\"291a3988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Smartflex empodera a las empresas de servicios p\u00fablicos para que a\u00f1adan a su oferta de valor servicios de telecomunicaciones como internet, VoIP, telefon\u00eda m\u00f3vil, televisi\u00f3n y plataformas de contenido. La soluci\u00f3n soporta diferentes plataformas y tecnolog\u00edas de comunicaci\u00f3n, gestiona los rangos de n\u00fameros y el inventario de direcciones IP, y controla los procesos de conexi\u00f3n\/desconexi\u00f3n de los servicios de telecomunicaciones, ayudando a las empresas a alcanzar mayores niveles de automatizaci\u00f3n y eficiencia, reducir la complejidad de TI y los costos de integraci\u00f3n, y aumentar la satisfacci\u00f3n de sus clientes con servicios de alta calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-8ce46ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"40212\" data-id=\"8ce46ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e60e3a6\" data-eae-slider=\"61716\" data-id=\"e60e3a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebc9ed0 elementor-widget elementor-widget-heading\" data-id=\"ebc9ed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">RETOS RELACIONADOS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f8ed1 elementor-widget elementor-widget-lae-posts-carousel\" data-id=\"84f8ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-posts-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div        id=\"lae-posts-carousel-6a575b44effe0\"\n        class=\"lae-posts-carousel lae-container lae-classic-skin\"\n        data-settings='{&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_speed&quot;:3000,&quot;animation_speed&quot;:300,&quot;pause_on_hover&quot;:true,&quot;adaptive_height&quot;:false,&quot;display_columns&quot;:3,&quot;scroll_columns&quot;:3,&quot;gutter&quot;:10,&quot;tablet_width&quot;:800,&quot;tablet_display_columns&quot;:2,&quot;tablet_scroll_columns&quot;:2,&quot;tablet_gutter&quot;:10,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1,&quot;mobile_gutter&quot;:10}'>\n<div data-id=\"id-12605\" class=\"lae-posts-carousel-item\">\n\n    <article id=\"post-12605\" class=\"post-12605 post type-post status-publish format-standard has-post-thumbnail hentry category-retos-de-industria-servicios-publicos category-solucion-analiticas category-solucion-cis category-solucion-css category-solucion-mdm category-solucion-mwm category-solucion-oss generate-columns tablet-grid-50 mobile-grid-100 grid-parent grid-33\">\n\n        \n            \n            \n            \n                <div class=\"lae-project-image\">\n\n                    \n                    \n                    \n                        <a href=\"https:\/\/www.openintl.com\/es\/que-tan-complejo-es-su-ecosistema-de-it\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-1024x576.jpg\" class=\"lae-image attachment-large size-large\" alt=\"holistic-solution-featured-image\" title=\"IT holistic solution - servicios p\u00fablicos\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-1024x576.jpg 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-300x169.jpg 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-768x432.jpg 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-600x338.jpg 600w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\n                    \n                    \n                        <div class=\"lae-image-info\">\n\n                            <div class=\"lae-entry-info\">\n\n                                \n                                    <h3 class=\"lae-post-title\">\n\n                                        <a href=\"https:\/\/www.openintl.com\/es\/que-tan-complejo-es-su-ecosistema-de-it\/\" title=\"\u00bfQu\u00e9 tan complejo es su ecosistema de IT?\"\n                                           rel=\"bookmark\">\u00bfQu\u00e9 tan complejo es su ecosistema de IT?<\/a>\n\n                                    <\/h3>\n\n                                \n                                \n                                    <span class=\"lae-terms\"><a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/\">Retos de industria - servicios p\u00fablicos<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-analiticas\/\">Soluci\u00f3n Anal\u00edticas<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-cis\/\">Soluci\u00f3n CIS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-css\/\">Soluci\u00f3n CSS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mdm\/\">Soluci\u00f3n MDM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mwm\/\">Soluci\u00f3n MWM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-oss\/\">Soluci\u00f3n OSS<\/a><\/span>\n                                \n                            <\/div>\n\n                        <\/div><!-- .lae-image-info -->\n\n                    \n                <\/div>\n\n            \n            \n                <div class=\"lae-entry-text-wrap \">\n\n                    \n                        <h3 class=\"entry-title\">\n\n                            <a href=\"https:\/\/www.openintl.com\/es\/que-tan-complejo-es-su-ecosistema-de-it\/\" title=\"\u00bfQu\u00e9 tan complejo es su ecosistema de IT?\"\n                               rel=\"bookmark\">\u00bfQu\u00e9 tan complejo es su ecosistema de IT?<\/a>\n\n                        <\/h3>\n\n                    \n                    \n                    \n                        <div class=\"entry-summary\">\n\n                            Evitar problemas de integraci\u00f3n ha llevado a los proveedores de servicios a buscar un \u00fanico sistema que gestione todo su ciclo de negocio a la velocidad necesaria para sobresalir en el nuevo mundo digital\n                        <\/div>\n\n                    \n                    \n                <\/div>\n\n            \n        \n    <\/article><!-- .hentry -->\n\n<\/div><!-- .lae-posts-carousel-item -->\n<div data-id=\"id-12587\" class=\"lae-posts-carousel-item\">\n\n    <article id=\"post-12587\" class=\"post-12587 post type-post status-publish format-standard has-post-thumbnail hentry category-retos-de-industria-servicios-publicos category-solucion-analiticas category-solucion-cis category-solucion-css category-solucion-mdm category-solucion-mwm category-solucion-oss generate-columns tablet-grid-50 mobile-grid-100 grid-parent grid-33\">\n\n        \n            \n            \n            \n                <div class=\"lae-project-image\">\n\n                    \n                    \n                    \n                        <a href=\"https:\/\/www.openintl.com\/es\/su-empresa-es-lo-suficientemente-flexible\/\"><img decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image-1024x707.jpg\" class=\"lae-image attachment-large size-large\" alt=\"new-business-models-featured-image\" title=\"Business models - reglas de negocio flexible\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image-1024x707.jpg 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image-300x207.jpg 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image-768x530.jpg 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image-600x414.jpg 600w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/new-business-models-featured-image.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\n                    \n                    \n                        <div class=\"lae-image-info\">\n\n                            <div class=\"lae-entry-info\">\n\n                                \n                                    <h3 class=\"lae-post-title\">\n\n                                        <a href=\"https:\/\/www.openintl.com\/es\/su-empresa-es-lo-suficientemente-flexible\/\" title=\"\u00bfEs su empresa lo suficientemente flexible?\"\n                                           rel=\"bookmark\">\u00bfEs su empresa lo suficientemente flexible?<\/a>\n\n                                    <\/h3>\n\n                                \n                                \n                                    <span class=\"lae-terms\"><a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/\">Retos de industria - servicios p\u00fablicos<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-analiticas\/\">Soluci\u00f3n Anal\u00edticas<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-cis\/\">Soluci\u00f3n CIS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-css\/\">Soluci\u00f3n CSS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mdm\/\">Soluci\u00f3n MDM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mwm\/\">Soluci\u00f3n MWM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-oss\/\">Soluci\u00f3n OSS<\/a><\/span>\n                                \n                            <\/div>\n\n                        <\/div><!-- .lae-image-info -->\n\n                    \n                <\/div>\n\n            \n            \n                <div class=\"lae-entry-text-wrap \">\n\n                    \n                        <h3 class=\"entry-title\">\n\n                            <a href=\"https:\/\/www.openintl.com\/es\/su-empresa-es-lo-suficientemente-flexible\/\" title=\"\u00bfEs su empresa lo suficientemente flexible?\"\n                               rel=\"bookmark\">\u00bfEs su empresa lo suficientemente flexible?<\/a>\n\n                        <\/h3>\n\n                    \n                    \n                    \n                        <div class=\"entry-summary\">\n\n                            Los proveedores de servicios deben tener la capacidad de ampliar el alcance funcional de sus soluciones de software para responder r\u00e1pidamente a las necesidades comerciales del mundo moderno\n                        <\/div>\n\n                    \n                    \n                <\/div>\n\n            \n        \n    <\/article><!-- .hentry -->\n\n<\/div><!-- .lae-posts-carousel-item -->\n<div data-id=\"id-12569\" class=\"lae-posts-carousel-item\">\n\n    <article id=\"post-12569\" class=\"post-12569 post type-post status-publish format-standard has-post-thumbnail hentry category-retos-de-industria-servicios-publicos category-solucion-analiticas category-solucion-cis category-solucion-css category-solucion-mdm category-solucion-mwm category-solucion-oss generate-columns tablet-grid-50 mobile-grid-100 grid-parent grid-33\">\n\n        \n            \n            \n            \n                <div class=\"lae-project-image\">\n\n                    \n                    \n                    \n                        <a href=\"https:\/\/www.openintl.com\/es\/esta-aprovechando-todos-los-beneficios-que-proporciona-la-nube\/\"><img decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image-1024x732.jpg\" class=\"lae-image attachment-large size-large\" alt=\"cloud-featured-image\" title=\"Servicios en la nube - Cloud\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image-1024x732.jpg 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image-300x214.jpg 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image-768x549.jpg 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image-600x429.jpg 600w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/cloud-featured-image.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\n                    \n                    \n                        <div class=\"lae-image-info\">\n\n                            <div class=\"lae-entry-info\">\n\n                                \n                                    <h3 class=\"lae-post-title\">\n\n                                        <a href=\"https:\/\/www.openintl.com\/es\/esta-aprovechando-todos-los-beneficios-que-proporciona-la-nube\/\" title=\"\u00bfEst\u00e1 aprovechando todos los beneficios que proporciona la nube?\"\n                                           rel=\"bookmark\">\u00bfEst\u00e1 aprovechando todos los beneficios que proporciona la nube?<\/a>\n\n                                    <\/h3>\n\n                                \n                                \n                                    <span class=\"lae-terms\"><a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/\">Retos de industria - servicios p\u00fablicos<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-analiticas\/\">Soluci\u00f3n Anal\u00edticas<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-cis\/\">Soluci\u00f3n CIS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-css\/\">Soluci\u00f3n CSS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mdm\/\">Soluci\u00f3n MDM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mwm\/\">Soluci\u00f3n MWM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-oss\/\">Soluci\u00f3n OSS<\/a><\/span>\n                                \n                            <\/div>\n\n                        <\/div><!-- .lae-image-info -->\n\n                    \n                <\/div>\n\n            \n            \n                <div class=\"lae-entry-text-wrap \">\n\n                    \n                        <h3 class=\"entry-title\">\n\n                            <a href=\"https:\/\/www.openintl.com\/es\/esta-aprovechando-todos-los-beneficios-que-proporciona-la-nube\/\" title=\"\u00bfEst\u00e1 aprovechando todos los beneficios que proporciona la nube?\"\n                               rel=\"bookmark\">\u00bfEst\u00e1 aprovechando todos los beneficios que proporciona la nube?<\/a>\n\n                        <\/h3>\n\n                    \n                    \n                    \n                        <div class=\"entry-summary\">\n\n                            Los proveedores de servicios deben buscar nuevas formas de soportar sus operaciones con tecnolog\u00eda \u00e1gil y confiable que tambi\u00e9n reduzca los costos\n                        <\/div>\n\n                    \n                    \n                <\/div>\n\n            \n        \n    <\/article><!-- .hentry -->\n\n<\/div><!-- .lae-posts-carousel-item -->\n<div data-id=\"id-12555\" class=\"lae-posts-carousel-item\">\n\n    <article id=\"post-12555\" class=\"post-12555 post type-post status-publish format-standard has-post-thumbnail hentry category-retos-de-industria-servicios-publicos category-solucion-analiticas category-solucion-cis category-solucion-css category-solucion-mdm category-solucion-mwm category-solucion-oss generate-columns tablet-grid-50 mobile-grid-100 grid-parent grid-33\">\n\n        \n            \n            \n            \n                <div class=\"lae-project-image\">\n\n                    \n                    \n                    \n                        <a href=\"https:\/\/www.openintl.com\/es\/esta-enfrentando-problemas-debido-al-envejecimiento-de-la-fuerza-laboral\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image-1024x683.jpg\" class=\"lae-image attachment-large size-large\" alt=\"obsolete-systems-featured-image\" title=\"Obsolete systems - El envejecimiento de la fuerza laboral\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image-1024x683.jpg 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image-300x200.jpg 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image-768x512.jpg 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image-600x400.jpg 600w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/obsolete-systems-featured-image.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\n                    \n                    \n                        <div class=\"lae-image-info\">\n\n                            <div class=\"lae-entry-info\">\n\n                                \n                                    <h3 class=\"lae-post-title\">\n\n                                        <a href=\"https:\/\/www.openintl.com\/es\/esta-enfrentando-problemas-debido-al-envejecimiento-de-la-fuerza-laboral\/\" title=\"\u00bfEst\u00e1 enfrentando problemas debido al envejecimiento de la fuerza laboral?\"\n                                           rel=\"bookmark\">\u00bfEst\u00e1 enfrentando problemas debido al envejecimiento de la fuerza laboral?<\/a>\n\n                                    <\/h3>\n\n                                \n                                \n                                    <span class=\"lae-terms\"><a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/\">Retos de industria - servicios p\u00fablicos<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-analiticas\/\">Soluci\u00f3n Anal\u00edticas<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-cis\/\">Soluci\u00f3n CIS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-css\/\">Soluci\u00f3n CSS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mdm\/\">Soluci\u00f3n MDM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mwm\/\">Soluci\u00f3n MWM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-oss\/\">Soluci\u00f3n OSS<\/a><\/span>\n                                \n                            <\/div>\n\n                        <\/div><!-- .lae-image-info -->\n\n                    \n                <\/div>\n\n            \n            \n                <div class=\"lae-entry-text-wrap \">\n\n                    \n                        <h3 class=\"entry-title\">\n\n                            <a href=\"https:\/\/www.openintl.com\/es\/esta-enfrentando-problemas-debido-al-envejecimiento-de-la-fuerza-laboral\/\" title=\"\u00bfEst\u00e1 enfrentando problemas debido al envejecimiento de la fuerza laboral?\"\n                               rel=\"bookmark\">\u00bfEst\u00e1 enfrentando problemas debido al envejecimiento de la fuerza laboral?<\/a>\n\n                        <\/h3>\n\n                    \n                    \n                    \n                        <div class=\"entry-summary\">\n\n                            La dificultad de encontrar expertos para soportar tecnolog\u00edas en desuso y los altos costos de mantener soluciones obsoletas son cada vez m\u00e1s preocupantes para los proveedores de servicios\n                        <\/div>\n\n                    \n                    \n                <\/div>\n\n            \n        \n    <\/article><!-- .hentry -->\n\n<\/div><!-- .lae-posts-carousel-item -->\n<div data-id=\"id-12442\" class=\"lae-posts-carousel-item\">\n\n    <article id=\"post-12442\" class=\"post-12442 post type-post status-publish format-standard has-post-thumbnail hentry category-retos-de-industria-servicios-publicos category-solucion-analiticas category-solucion-cis category-solucion-css category-solucion-mdm category-solucion-mwm category-solucion-oss generate-columns tablet-grid-50 mobile-grid-100 grid-parent grid-33\">\n\n        \n            \n            \n            \n                <div class=\"lae-project-image\">\n\n                    \n                    \n                    \n                        <a href=\"https:\/\/www.openintl.com\/es\/puede-su-sistema-abordar-los-desafios-del-manana\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image-1024x683.jpg\" class=\"lae-image attachment-large size-large\" alt=\"digital-business-featured-image\" title=\"Digital Transformation - Transformaci\u00f3n Digital\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image-1024x683.jpg 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image-300x200.jpg 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image-768x512.jpg 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image-600x400.jpg 600w, https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/digital-business-featured-image.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\n                    \n                    \n                        <div class=\"lae-image-info\">\n\n                            <div class=\"lae-entry-info\">\n\n                                \n                                    <h3 class=\"lae-post-title\">\n\n                                        <a href=\"https:\/\/www.openintl.com\/es\/puede-su-sistema-abordar-los-desafios-del-manana\/\" title=\"\u00bfPuede su sistema actual abordar los desaf\u00edos del ma\u00f1ana?\"\n                                           rel=\"bookmark\">\u00bfPuede su sistema actual abordar los desaf\u00edos del ma\u00f1ana?<\/a>\n\n                                    <\/h3>\n\n                                \n                                \n                                    <span class=\"lae-terms\"><a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/\">Retos de industria - servicios p\u00fablicos<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-analiticas\/\">Soluci\u00f3n Anal\u00edticas<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-cis\/\">Soluci\u00f3n CIS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-css\/\">Soluci\u00f3n CSS<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mdm\/\">Soluci\u00f3n MDM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-mwm\/\">Soluci\u00f3n MWM<\/a>, <a href=\"https:\/\/www.openintl.com\/es\/category\/retos-de-industria-servicios-publicos\/solucion-oss\/\">Soluci\u00f3n OSS<\/a><\/span>\n                                \n                            <\/div>\n\n                        <\/div><!-- .lae-image-info -->\n\n                    \n                <\/div>\n\n            \n            \n                <div class=\"lae-entry-text-wrap \">\n\n                    \n                        <h3 class=\"entry-title\">\n\n                            <a href=\"https:\/\/www.openintl.com\/es\/puede-su-sistema-abordar-los-desafios-del-manana\/\" title=\"\u00bfPuede su sistema actual abordar los desaf\u00edos del ma\u00f1ana?\"\n                               rel=\"bookmark\">\u00bfPuede su sistema actual abordar los desaf\u00edos del ma\u00f1ana?<\/a>\n\n                        <\/h3>\n\n                    \n                    \n                    \n                        <div class=\"entry-summary\">\n\n                            La transformaci\u00f3n digital es una realidad para los proveedores de servicios quienes deben enfrentarla adaptando sus operaciones y procesos a las \u00faltimas tecnolog\u00edas que ofrece el mercado\n                        <\/div>\n\n                    \n                    \n                <\/div>\n\n            \n        \n    <\/article><!-- .hentry -->\n\n<\/div><!-- .lae-posts-carousel-item --><\/div><!-- .lae-posts-carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-1453a021 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"95440\" data-id=\"1453a021\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b89cde5\" data-eae-slider=\"73002\" data-id=\"b89cde5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac4ba21 elementor-widget elementor-widget-heading\" data-id=\"4ac4ba21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Perm\u00edtanos mostrarle c\u00f3mo podemos ayudarlo a mejorar el rendimiento de su compa\u00f1\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9e727d elementor-widget elementor-widget-text-editor\" data-id=\"f9e727d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Empoderando<\/strong> su negocio\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61affb6f\" data-eae-slider=\"2917\" data-id=\"61affb6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-990fa00 elementor-button-info elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"990fa00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/app.openintl.com\/es\/demo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER DEMO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":89,"featured_media":0,"parent":13309,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-13305","page","type-page","status-publish","hentry","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>OSS - Sistema de Soporte a la Operaci\u00f3n | Smartflex<\/title>\n<meta name=\"description\" content=\"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OSS | Sistema de Soporte a la Operaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Intelligence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OpenSmartflex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T15:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/09\/Operation-Support-System.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/\",\"name\":\"OSS - Sistema de Soporte a la Operaci\u00f3n | Smartflex\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/holistic-solution-featured-image-1024x576.jpg\",\"datePublished\":\"2019-09-02T22:38:52+00:00\",\"dateModified\":\"2023-06-09T15:19:15+00:00\",\"description\":\"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/holistic-solution-featured-image-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/holistic-solution-featured-image-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/sistema-de-soporte-a-la-operacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plataforma\",\"item\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/plataforma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OSS | Sistema de Soporte a la Operaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Open Intelligence\",\"description\":\"Software for utility companies\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"alternateName\":\"Open\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Open Intelligence\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-color-open-intelligence-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-color-open-intelligence-logo-1.png\",\"width\":974,\"height\":378,\"caption\":\"Open Intelligence\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OpenSmartflex\\\/\",\"https:\\\/\\\/x.com\\\/opensmartflex\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/weareopenintelligence\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHpHSdiqVTs0OvdEYJxCqiQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"OSS - Sistema de Soporte a la Operaci\u00f3n | Smartflex","description":"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/","og_locale":"es_ES","og_type":"article","og_title":"OSS | Sistema de Soporte a la Operaci\u00f3n","og_description":"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red","og_url":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/","og_site_name":"Open Intelligence","article_publisher":"https:\/\/www.facebook.com\/OpenSmartflex\/","article_modified_time":"2023-06-09T15:19:15+00:00","og_image":[{"url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/09\/Operation-Support-System.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@opensmartflex","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/","url":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/","name":"OSS - Sistema de Soporte a la Operaci\u00f3n | Smartflex","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/#primaryimage"},"image":{"@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-1024x576.jpg","datePublished":"2019-09-02T22:38:52+00:00","dateModified":"2023-06-09T15:19:15+00:00","description":"Smartflex OSS - Sistema de Soporte a la Operaci\u00f3n alcanza los niveles m\u00e1s altos de automatizaci\u00f3n y eficiencia del inventario de la red","breadcrumb":{"@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/#primaryimage","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-1024x576.jpg","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2019\/05\/holistic-solution-featured-image-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.openintl.com\/es\/plataforma\/sistema-de-soporte-a-la-operacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.openintl.com\/es\/"},{"@type":"ListItem","position":2,"name":"Plataforma","item":"https:\/\/www.openintl.com\/es\/plataforma\/"},{"@type":"ListItem","position":3,"name":"OSS | Sistema de Soporte a la Operaci\u00f3n"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Open Intelligence","description":"Software for utility companies","publisher":{"@id":"\/#organization"},"alternateName":"Open","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"\/#organization","name":"Open Intelligence","url":"\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","width":974,"height":378,"caption":"Open Intelligence"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OpenSmartflex\/","https:\/\/x.com\/opensmartflex","https:\/\/www.linkedin.com\/company\/weareopenintelligence","https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/pages\/13305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/comments?post=13305"}],"version-history":[{"count":1,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/pages\/13305\/revisions"}],"predecessor-version":[{"id":31478,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/pages\/13305\/revisions\/31478"}],"up":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/pages\/13309"}],"wp:attachment":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media?parent=13305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}