{"id":10161,"date":"2018-09-21T11:03:53","date_gmt":"2018-09-21T16:03:53","guid":{"rendered":"https:\/\/www.openintl.com\/ambienteWordpress\/?p=10161"},"modified":"2022-09-23T10:05:49","modified_gmt":"2022-09-23T15:05:49","slug":"open-news-septiembre","status":"publish","type":"post","link":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/","title":{"rendered":"Open News &#8211; Septiembre"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10161\" class=\"elementor elementor-10161\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-702588ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"66902\" data-id=\"702588ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78821503\" data-eae-slider=\"23010\" data-id=\"78821503\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e093477 elementor-widget elementor-widget-text-editor\" data-id=\"3e093477\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><iframe src=\"https:\/\/preview.hs-sites.com\/_hcms\/preview\/content\/6196539905?portalId=2545432&amp;_preview=true&amp;cacheBust=0&amp;preview_key=bYhdWFGr&amp;from_buffer=false\" width=\"798\" height=\"1500\"><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Open News &#8211; September<\/p>\n","protected":false},"author":89,"featured_media":9924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4313],"tags":[],"class_list":["post-10161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opennews","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Open News - Septiembre | Open Intelligence<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open News - Septiembre\" \/>\n<meta property=\"og:description\" content=\"Open News - September\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Intelligence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OpenSmartflex\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-21T16:03:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T15:05:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1054\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GrowthMK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:site\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GrowthMK\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\"},\"author\":{\"name\":\"GrowthMK\",\"@id\":\"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d\"},\"headline\":\"Open News &#8211; Septiembre\",\"datePublished\":\"2018-09-21T16:03:53+00:00\",\"dateModified\":\"2022-09-23T15:05:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg\",\"articleSection\":[\"Open News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\",\"url\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\",\"name\":\"Open News - Septiembre | Open Intelligence\",\"isPartOf\":{\"@id\":\"\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg\",\"datePublished\":\"2018-09-21T16:03:53+00:00\",\"dateModified\":\"2022-09-23T15:05:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage\",\"url\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg\",\"contentUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg\",\"width\":1054,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.openintl.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open News &#8211; Septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/#website\",\"url\":\"\/\",\"name\":\"Open Intelligence\",\"description\":\"Software for utility companies\",\"publisher\":{\"@id\":\"\/#organization\"},\"alternateName\":\"Open\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"\/#organization\",\"name\":\"Open Intelligence\",\"url\":\"\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png\",\"contentUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png\",\"width\":974,\"height\":378,\"caption\":\"Open Intelligence\"},\"image\":{\"@id\":\"\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OpenSmartflex\/\",\"https:\/\/x.com\/opensmartflex\",\"https:\/\/www.linkedin.com\/company\/weareopenintelligence\",\"https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ\"]},{\"@type\":\"Person\",\"@id\":\"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d\",\"name\":\"GrowthMK\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open News - Septiembre | Open Intelligence","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Open News - Septiembre","og_description":"Open News - September","og_url":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/","og_site_name":"Open Intelligence","article_publisher":"https:\/\/www.facebook.com\/OpenSmartflex\/","article_published_time":"2018-09-21T16:03:53+00:00","article_modified_time":"2022-09-23T15:05:49+00:00","og_image":[{"width":1054,"height":703,"url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg","type":"image\/jpeg"}],"author":"GrowthMK","twitter_card":"summary_large_image","twitter_creator":"@opensmartflex","twitter_site":"@opensmartflex","twitter_misc":{"Escrito por":"GrowthMK"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#article","isPartOf":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/"},"author":{"name":"GrowthMK","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d"},"headline":"Open News &#8211; Septiembre","datePublished":"2018-09-21T16:03:53+00:00","dateModified":"2022-09-23T15:05:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/"},"wordCount":4,"publisher":{"@id":"\/#organization"},"image":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg","articleSection":["Open News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/","url":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/","name":"Open News - Septiembre | Open Intelligence","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg","datePublished":"2018-09-21T16:03:53+00:00","dateModified":"2022-09-23T15:05:49+00:00","breadcrumb":{"@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.openintl.com\/es\/open-news-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#primaryimage","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2018\/08\/open-news-thumbnail.jpg","width":1054,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/www.openintl.com\/es\/open-news-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.openintl.com\/es\/"},{"@type":"ListItem","position":2,"name":"Open News &#8211; Septiembre"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Open Intelligence","description":"Software for utility companies","publisher":{"@id":"\/#organization"},"alternateName":"Open","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"\/#organization","name":"Open Intelligence","url":"\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","width":974,"height":378,"caption":"Open Intelligence"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OpenSmartflex\/","https:\/\/x.com\/opensmartflex","https:\/\/www.linkedin.com\/company\/weareopenintelligence","https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ"]},{"@type":"Person","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d","name":"GrowthMK"}]}},"_links":{"self":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/10161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/comments?post=10161"}],"version-history":[{"count":0,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/10161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media\/9924"}],"wp:attachment":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media?parent=10161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/categories?post=10161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/tags?post=10161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}