{"id":15749,"date":"2020-04-23T10:05:16","date_gmt":"2020-04-23T15:05:16","guid":{"rendered":"https:\/\/www.openintl.com\/ambienteWordpress\/?p=15749"},"modified":"2022-09-23T10:04:26","modified_gmt":"2022-09-23T15:04:26","slug":"como-afectan-los-eventos-disruptivos-las-empresas-de-servicios-publicos","status":"publish","type":"post","link":"https:\/\/www.openintl.com\/es\/como-afectan-los-eventos-disruptivos-las-empresas-de-servicios-publicos\/","title":{"rendered":"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15749\" class=\"elementor elementor-15749 elementor-15685\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-34e04786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"6405\" data-id=\"34e04786\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66a80efe\" data-eae-slider=\"15967\" data-id=\"66a80efe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ebe027 elementor-widget elementor-widget-text-editor\" data-id=\"1ebe027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: rgb(0, 50, 89); font-family: Montserrat, sans-serif; font-size: 28px; font-style: inherit; font-weight: 700;\">Cualquier crisis, como la actual pandemia del COVID-19, puede exponer qu\u00e9 tan vulnerables son las operaciones de una empresa cuando \u00e9sta se enfrenta a situaciones dif\u00edciles. Sin tiempo de preparaci\u00f3n para enfrentar esas situaciones complejas, los responsables de la toma de decisiones est\u00e1n reflexionando sobre c\u00f3mo los eventos disruptivos pueden afectar las operaciones diarias.<\/span><br><\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n<div>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-15752 aligncenter\" src=\"https:\/\/www.openintl.com\/\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1.png\" alt=\"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\" width=\"1275\" height=\"473\" srcset=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1.png 1275w, https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1-300x111.png 300w, https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1-1024x380.png 1024w, https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1-768x285.png 768w, https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19-1-600x223.png 600w\" sizes=\"(max-width: 1275px) 100vw, 1275px\" \/>Cuando eventos fuertemente disruptivos ocurren a escala global, pueden tener un gran efecto tanto en las rutinas de las personas como en las operaciones de las empresas. Las organizaciones, como los proveedores de servicios, necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.<\/p>\n<p>Esto no solo aplica al COVID-19, sino que se puede extender a varios escenarios extremos que, aunque poco probables, son factibles. \u00bfQu\u00e9 se puede hacer para enfrentar ataques terroristas o desastres naturales que pueden da\u00f1ar la infraestructura? \u00bfC\u00f3mo mantener el flujo de caja durante una recesi\u00f3n econ\u00f3mica que afecta por igual a clientes y empresas? \u00bfC\u00f3mo pueden las organizaciones mantener niveles de productividad altos con una fuerza laboral reducida debido al aislamiento? Estas preguntas se han convertido en una de las principales preocupaciones estrat\u00e9gicas para los proveedores de servicios y dem\u00e1s empresas a la hora de evaluar el impacto de posibles calamidades futuras.<\/p>\n<p>Las empresas de servicios p\u00fablicos deben implementar <a href=\"https:\/\/www.openintl.com\/\/es\/el-papel-de-las-empresas-de-servicios-publicos-covid-19\/\"><strong><u>medidas financieras para ayudar a sus clientes <\/u><u>durante esas situaciones dif\u00edciles<\/u><\/strong><\/a>. Sin embargo, estas medidas plantean un problema fundamental: \u00bfC\u00f3mo pueden las empresas de servicios p\u00fablicos asegurar ingresos mientras tienen plazos de pago laxos? Estas organizaciones necesitan mantener la eficiencia de sus operaciones asignando cuadrillas de campo para reconectar a los clientes, garantizando el suministro del servicio, al tiempo que cumplen con las medidas de salud para prevenir el contacto social.<\/p>\n<p>Bajo estas circunstancias, <a href=\"https:\/\/www.openintl.com\/\/es\/enfrentando-los-desafios-del-covid-19-con-open-smartflex\/\"><strong><u>la tecnolog\u00eda se vuelve crucial<\/u><\/strong><\/a>&nbsp;para mitigar los riesgos asociados con esos procedimientos; \u00e9sta ayuda a los proveedores de servicios a implementar iniciativas \u00fatiles mientras que mantiene su contabilidad y procesos internos organizados. Por ende, su soluci\u00f3n tecnol\u00f3gica debe soportar cuatro actores principales que hacen parte del negocio:<\/p>\n<ol>\n<li>Los clientes: las empresas de servicios p\u00fablicos pueden apoyar a sus clientes d\u00e1ndoles alternativas de pago flexibles y asegurando el suministro, mientras ofrecen una experiencia digital excepcional. Las utilities deben introducir nuevos canales de comunicaci\u00f3n para mantener a sus clientes comprometidos e informados.<\/li>\n<li>El personal de la compa\u00f1\u00eda: las empresas de servicios p\u00fablicos deben habilitar modalidades de trabajo en casa y ajustar los procedimientos de servicio a trav\u00e9s de flujos de trabajo flexibles, manteniendo los procesos de cara al cliente en funcionamiento con la ayuda de una sola vista 360\u00b0 de transacciones e interacciones. Adicionalmente, deben brindar diferentes canales de contacto y herramientas de servicio para ayudar al personal cuando trabajen de forma remota.<\/li>\n<li>Contratistas y cuadrillas de campo: al ajustar los procesos de trabajo de campo y brindar procedimiento seguros y trazabilidad para realizar actividades en sitio, las empresas de servicios p\u00fablicos pueden asegurar la protecci\u00f3n de sus cuadrillas de campo y contratistas.<\/li>\n<li>La organizaci\u00f3n: creando planes de cobro centrados en el cliente y gestionando cuentas por cobrar, acuerdos de pago y otros mecanismos, las empresas de servicios p\u00fablicos pueden normalizar las fuentes de ingresos y asegurar su estabilidad financiera.<\/li>\n<\/ol>\n<p>Sin embargo, la implementaci\u00f3n de estas iniciativas conlleva varios problemas para los proveedores de servicios. Se necesitan modificaciones y sincronizaciones en m\u00faltiples sistemas, las interfaces deben ser actualizadas para crear experiencias de usuario coherentes, hay que coordinar varios proveedores para orquestar sus funcionalidades por m\u00f3dulos y las integraciones deben ser probadas adecuadamente antes de la puesta en marcha. Todas estas dificultades agravan una situaci\u00f3n ya angustiosa y aumentan los esfuerzos y los costos de manera exponencial.<\/p>\n<p>Estos obst\u00e1culos pueden superarse con un CIS hol\u00edstico flexible capaz de soportar completamente las operaciones en el dominio del cliente.&nbsp; La soluci\u00f3n debe tener un alcance expandido que incluya funcionalidades de autoservicio del cliente (CSS), relacionamiento con el cliente (CRM), gesti\u00f3n de la fuerza de trabajo m\u00f3vil (MWM) y gesti\u00f3n de datos medidores (MDM), entregadas on-premise o en un ambiente cloud. A trav\u00e9s de la implementaci\u00f3n de tecnolog\u00eda con estas caracter\u00edsticas, los proveedores de servicios pueden continuar operando sin importar qu\u00e9 tan desafiantes sean los escenarios comerciales, mientras reducen el Costo Total de Propiedad (TCO). Esto les permitir\u00e1 cambiar el enfoque de inversiones no rentables en sistemas de integraci\u00f3n a inversiones en mejoras funcionales.<\/p>\n<p>La situaci\u00f3n que se ha generado en torno al COVID-19 demuestra que, sin importar cuanto planeemos, es imposible predecir ese tipo de crisis. Sin embargo, las empresas de servicios p\u00fablicos deben tomar medidas proactivas para soportar sus procesos operativos clave, de manera que puedan continuar operando con \u00e9xito durante esos tiempos y seguir haci\u00e9ndolo a largo plazo.<\/p>\n<\/div>\n<p><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\"><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.<\/p>\n","protected":false},"author":89,"featured_media":15750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[72,9092],"tags":[],"class_list":["post-15749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-industria","category-covid19-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfAfectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?<\/title>\n<meta name=\"description\" content=\"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\" \/>\n<meta property=\"og:description\" content=\"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Intelligence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OpenSmartflex\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-23T15:05:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T15:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GrowthMK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:site\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GrowthMK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/\"},\"author\":{\"name\":\"GrowthMK\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/0d317ba2be1e61522428c1e7bd4c222d\"},\"headline\":\"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\",\"datePublished\":\"2020-04-23T15:05:16+00:00\",\"dateModified\":\"2022-09-23T15:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/\"},\"wordCount\":835,\"publisher\":{\"@id\":\"\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/eventos-disruptivos-covid-19.jpg\",\"articleSection\":[\"Art\u00edculos de industria\",\"Covid-19\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/\",\"name\":\"\u00bfAfectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/eventos-disruptivos-covid-19.jpg\",\"datePublished\":\"2020-04-23T15:05:16+00:00\",\"dateModified\":\"2022-09-23T15:04:26+00:00\",\"description\":\"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/eventos-disruptivos-covid-19.jpg\",\"contentUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/eventos-disruptivos-covid-19.jpg\",\"width\":1500,\"height\":984,\"caption\":\"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.openintl.com\\\/how-disruptive-events-affect-utilities-operations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.openintl.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Open Intelligence\",\"description\":\"Software for utility companies\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"alternateName\":\"Open\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Open Intelligence\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-color-open-intelligence-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.openintl.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-color-open-intelligence-logo-1.png\",\"width\":974,\"height\":378,\"caption\":\"Open Intelligence\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OpenSmartflex\\\/\",\"https:\\\/\\\/x.com\\\/opensmartflex\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/weareopenintelligence\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHpHSdiqVTs0OvdEYJxCqiQ\"]},{\"@type\":\"Person\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/0d317ba2be1e61522428c1e7bd4c222d\",\"name\":\"GrowthMK\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfAfectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?","description":"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?","og_description":"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.","og_url":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/","og_site_name":"Open Intelligence","article_publisher":"https:\/\/www.facebook.com\/OpenSmartflex\/","article_published_time":"2020-04-23T15:05:16+00:00","article_modified_time":"2022-09-23T15:04:26+00:00","og_image":[{"width":1500,"height":984,"url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg","type":"image\/jpeg"}],"author":"GrowthMK","twitter_card":"summary_large_image","twitter_creator":"@opensmartflex","twitter_site":"@opensmartflex","twitter_misc":{"Escrito por":"GrowthMK","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#article","isPartOf":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/"},"author":{"name":"GrowthMK","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d"},"headline":"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?","datePublished":"2020-04-23T15:05:16+00:00","dateModified":"2022-09-23T15:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/"},"wordCount":835,"publisher":{"@id":"\/#organization"},"image":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg","articleSection":["Art\u00edculos de industria","Covid-19"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/","url":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/","name":"\u00bfAfectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#primaryimage"},"image":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg","datePublished":"2020-04-23T15:05:16+00:00","dateModified":"2022-09-23T15:04:26+00:00","description":"Ante eventos disruptivos, los proveedores de servicios necesitan mitigar los riesgos emergentes que pueden impedir que sus negocios operen con normalidad.","breadcrumb":{"@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#primaryimage","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2020\/04\/eventos-disruptivos-covid-19.jpg","width":1500,"height":984,"caption":"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.openintl.com\/how-disruptive-events-affect-utilities-operations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.openintl.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo afectan los eventos disruptivos las operaciones de las empresas de servicios p\u00fablicos?"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Open Intelligence","description":"Software for utility companies","publisher":{"@id":"\/#organization"},"alternateName":"Open","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"\/#organization","name":"Open Intelligence","url":"\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","width":974,"height":378,"caption":"Open Intelligence"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OpenSmartflex\/","https:\/\/x.com\/opensmartflex","https:\/\/www.linkedin.com\/company\/weareopenintelligence","https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ"]},{"@type":"Person","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d","name":"GrowthMK"}]}},"_links":{"self":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/15749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/comments?post=15749"}],"version-history":[{"count":0,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/15749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media\/15750"}],"wp:attachment":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media?parent=15749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/categories?post=15749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/tags?post=15749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}