{"id":25343,"date":"2022-07-18T16:35:18","date_gmt":"2022-07-18T21:35:18","guid":{"rendered":"https:\/\/www.openintl.com\/ambienteTrabajo2\/?p=25343"},"modified":"2022-09-23T10:03:42","modified_gmt":"2022-09-23T15:03:42","slug":"open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas","status":"publish","type":"post","link":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/","title":{"rendered":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25343\" class=\"elementor elementor-25343 elementor-25333\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-3c34123e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"3338\" data-id=\"3c34123e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-442b4d41\" data-eae-slider=\"730\" data-id=\"442b4d41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-325dcffa elementor-widget elementor-widget-text-editor\" data-id=\"325dcffa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 28px; text-align: center;\">Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e4d56c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"54360\" data-id=\"e4d56c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0956cb4\" data-eae-slider=\"8958\" data-id=\"0956cb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07448fd elementor-widget elementor-widget-text-editor\" data-id=\"07448fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, ofrecer\u00e1 una conferencia donde expondr\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.\u00a0<\/p><p>Esta sesi\u00f3n tendr\u00e1 lugar el pr\u00f3ximo martes 26 de julio de 2022 en Austin, TX, y en ella, los oradores, Juan Corredor, CTO de Open y Felipe Corredor, Industry Consultant, mostrar\u00e1n c\u00f3mo crear nuevos procesos digitales enriquecidos con inteligencia artificial y motores de reglas de negocios, ideales para las empresas de servicios p\u00fablicos que buscan hacer m\u00e1s eficientes sus operaciones con herramientas innovadoras.\u00a0<\/p><p>En la conferencia tambi\u00e9n\u00a0 se explicar\u00e1\u00a0 c\u00f3mo funcionan las herramientas conversacionales con un CIS moderno.\u00a0 Al respecto,\u00a0 Felipe Corredor, afirma:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b62b9b7 elementor-widget elementor-widget-tp-blockquote\" data-id=\"b62b9b7\" data-element_type=\"widget\" data-widget_type=\"tp-blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"plus_blockquote quote-style-1   none \" ><blockquote class=\"quote-text\"><span class=\"tp-bq-desc\"><p><em>\u201cQueremos mostrarle a las empresas de servicios p\u00fablicos casos concretos en los que puedan ver las ventajas que tiene incorporar la Inteligencia Artificial (IA) en su caja de herramientas para brindar a sus clientes experiencias superiores impulsadas por nuevas tecnolog\u00edas y aplicaciones de software, en particular, chatbots, asistentes virtuales y flujos de trabajo inteligentes\u201d.<\/em><\/p><\/span><\/blockquote><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b949b61 elementor-widget elementor-widget-text-editor\" data-id=\"b949b61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Por su parte, Juan Corredor concluy\u00f3:<\/em><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f39c12 elementor-widget elementor-widget-tp-blockquote\" data-id=\"9f39c12\" data-element_type=\"widget\" data-widget_type=\"tp-blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"plus_blockquote quote-style-1   none \" ><blockquote class=\"quote-text\"><span class=\"tp-bq-desc\"><p><em>\u201cEn Open, hemos estado trabajando en la creaci\u00f3n de <a href=\"https:\/\/www.openintl.com\/es\/interacciones-proactivas\/\">una soluci\u00f3n cognitiva enriquecida con IA<\/a>, en combinaci\u00f3n con otras tecnolog\u00edas emergentes para transformar digitalmente a las empresas de servicios p\u00fablicos. Con esto hemos creado una nueva forma para que estas empresas interact\u00faen con sus clientes de manera eficiente y personalizada, anticip\u00e1ndose a sus necesidades, a trav\u00e9s de la inteligencia artificial y las anal\u00edticas de datos. Estamos ansiosos de compartir nuestro conocimiento de industria y nuestra soluci\u00f3n con todos en la TPPA Annual Meeting\u201d<\/em><\/p><\/span><\/blockquote><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b19c63 elementor-widget elementor-widget-text-editor\" data-id=\"3b19c63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>La reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) se llevar\u00e1 del 25 al 27 de julio de 2022; all\u00ed, profesionales de toda la industria se reunir\u00e1n para compartir sus conocimientos y experiencias sobre\u00a0 los retos y el futuro de la industria de energ\u00eda.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.<\/p>\n","protected":false},"author":89,"featured_media":25338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-25343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas<\/title>\n<meta name=\"description\" content=\"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas\" \/>\n<meta property=\"og:description\" content=\"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Intelligence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OpenSmartflex\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T21:35:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T15:03:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GrowthMK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:site\" content=\"@opensmartflex\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GrowthMK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\"},\"author\":{\"name\":\"GrowthMK\",\"@id\":\"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d\"},\"headline\":\"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas\",\"datePublished\":\"2022-07-18T21:35:18+00:00\",\"dateModified\":\"2022-09-23T15:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\"},\"wordCount\":433,\"publisher\":{\"@id\":\"\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\",\"url\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\",\"name\":\"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas\",\"isPartOf\":{\"@id\":\"\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg\",\"datePublished\":\"2022-07-18T21:35:18+00:00\",\"dateModified\":\"2022-09-23T15:03:42+00:00\",\"description\":\"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage\",\"url\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg\",\"contentUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.openintl.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/#website\",\"url\":\"\/\",\"name\":\"Open Intelligence\",\"description\":\"Software for utility companies\",\"publisher\":{\"@id\":\"\/#organization\"},\"alternateName\":\"Open\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"\/#organization\",\"name\":\"Open Intelligence\",\"url\":\"\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png\",\"contentUrl\":\"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png\",\"width\":974,\"height\":378,\"caption\":\"Open Intelligence\"},\"image\":{\"@id\":\"\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OpenSmartflex\/\",\"https:\/\/x.com\/opensmartflex\",\"https:\/\/www.linkedin.com\/company\/weareopenintelligence\",\"https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ\"]},{\"@type\":\"Person\",\"@id\":\"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d\",\"name\":\"GrowthMK\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas","description":"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/","og_locale":"es_ES","og_type":"article","og_title":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas","og_description":"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.","og_url":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/","og_site_name":"Open Intelligence","article_publisher":"https:\/\/www.facebook.com\/OpenSmartflex\/","article_published_time":"2022-07-18T21:35:18+00:00","article_modified_time":"2022-09-23T15:03:42+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg","type":"image\/jpeg"}],"author":"GrowthMK","twitter_card":"summary_large_image","twitter_creator":"@opensmartflex","twitter_site":"@opensmartflex","twitter_misc":{"Escrito por":"GrowthMK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#article","isPartOf":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/"},"author":{"name":"GrowthMK","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d"},"headline":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas","datePublished":"2022-07-18T21:35:18+00:00","dateModified":"2022-09-23T15:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/"},"wordCount":433,"publisher":{"@id":"\/#organization"},"image":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/","url":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/","name":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage"},"image":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg","datePublished":"2022-07-18T21:35:18+00:00","dateModified":"2022-09-23T15:03:42+00:00","description":"Durante la reuni\u00f3n anual de la Asociaci\u00f3n de Energ\u00eda P\u00fablica de Texas (TPPA) en Estados Unidos, Open Intelligence, empresa l\u00edder del mercado de soluciones tecnol\u00f3gicas especializadas en servicios p\u00fablicos, liderar\u00e1 una conferencia donde mostrar\u00e1 c\u00f3mo la inteligencia artificial ayuda a mejorar la experiencia de los clientes de este sector.","breadcrumb":{"@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#primaryimage","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/07\/tppa_2022_2.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.openintl.com\/es\/open-intelligence-liderara-conferencia-sobre-implementacion-de-inteligencia-artificial-en-empresas-de-servicios-publicos-en-la-conferencia-anual-de-la-tppa-en-texas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.openintl.com\/es\/"},{"@type":"ListItem","position":2,"name":"Open Intelligence liderar\u00e1 conferencia sobre implementaci\u00f3n de inteligencia artificial en empresas de servicios p\u00fablicos, en la conferencia anual de la TPPA en Texas"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Open Intelligence","description":"Software for utility companies","publisher":{"@id":"\/#organization"},"alternateName":"Open","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"\/#organization","name":"Open Intelligence","url":"\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","contentUrl":"https:\/\/www.openintl.com\/wp-content\/uploads\/2022\/09\/cropped-color-open-intelligence-logo-1.png","width":974,"height":378,"caption":"Open Intelligence"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OpenSmartflex\/","https:\/\/x.com\/opensmartflex","https:\/\/www.linkedin.com\/company\/weareopenintelligence","https:\/\/www.youtube.com\/channel\/UCHpHSdiqVTs0OvdEYJxCqiQ"]},{"@type":"Person","@id":"\/#\/schema\/person\/0d317ba2be1e61522428c1e7bd4c222d","name":"GrowthMK"}]}},"_links":{"self":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/25343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/comments?post=25343"}],"version-history":[{"count":0,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/posts\/25343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media\/25338"}],"wp:attachment":[{"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/media?parent=25343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/categories?post=25343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.openintl.com\/es\/wp-json\/wp\/v2\/tags?post=25343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}